{"id":229,"date":"2021-12-16T14:04:49","date_gmt":"2021-12-16T13:04:49","guid":{"rendered":"https:\/\/www.fishy-style.com\/?p=229\/"},"modified":"2021-12-20T15:34:49","modified_gmt":"2021-12-20T14:34:49","slug":"come-pescare-con-la-treccia","status":"publish","type":"post","link":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/","title":{"rendered":"Come pescare con la treccia?"},"content":{"rendered":"\n<p>La treccia \u00e8 uno degli elementi che vi sar\u00e0 di grande aiuto quando si tratta di pesca. Affinch\u00e9 vi serva al meglio, \u00e8 importante sceglierlo con cura. Se prendete le iniziative giuste per questo accessorio, sarete in grado di catturare grandi pesci nel migliore dei modi.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La differenza tra nylon e filo intrecciato<\/h2>\n\n\n\n<p>Per pescare bene con un <strong><a href=\"https:\/\/www.nootica.it\/pesca\/pesca-esotica\/treccia.html\">treccia da pesca<\/a><\/strong>Il primo passo \u00e8 quello di confrontarlo con l&#8217;altra principale alternativa, il nylon. Quest&#8217;ultimo \u00e8 pi\u00f9 adatto alla pesca per i principianti, soprattutto a causa del suo prezzo basso. Tuttavia, avrete esigenze pi\u00f9 specifiche man mano che andate avanti.<\/p>\n\n\n\n<p>Il dettaglio principale che differenzia il nylon dalla treccia \u00e8 che quest&#8217;ultima \u00e8 molto meno elastica. Il nylon mostrer\u00e0 questa propriet\u00e0 poco pratica non appena si passer\u00e0 a giochi pi\u00f9 grandi. Non c&#8217;\u00e8 bisogno di preoccuparsi di questo quando si tratta di treccia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Adattamento alle condizioni di pesca<\/h2>\n\n\n\n<p>Se la treccia \u00e8 pi\u00f9 adatta a uno stile di pesca pi\u00f9 elaborato, allora il passo successivo \u00e8 quello di scegliere la <strong>treccia da pesca<\/strong> giusta. Ci sono molti dettagli da considerare quando si sceglie una lenza. Questi includono il diametro, la forza e molti altri dettagli.<\/p>\n\n\n\n<p>Il pesce che si vuole catturare, ma anche le condizioni di pesca stesse, sono elementi che influenzano il materiale da utilizzare. Dovete assicurarvi di scegliere l&#8217;opzione pi\u00f9 adatta alle condizioni di pesca in cui andrete. A seconda del caso, un tipo di treccia sar\u00e0 pi\u00f9 adatto di un altro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Capire l&#8217;importanza del numero di fili<\/h2>\n\n\n\n<p>A differenza del nylon, una <strong>treccia da pesca<\/strong> comprender\u00e0 diversi fili. Si parte da 4 fili, ma il numero di fili pu\u00f2 andare fino a 8, 12 o anche 16 fili. Minore \u00e8 il numero di fili, migliore \u00e8 la resistenza alle acque abrasive. Pi\u00f9 fili ci sono, pi\u00f9 la linea pu\u00f2 essere lanciata lontano.<\/p>\n\n\n\n<p>Il numero di fili aumenter\u00e0 anche la resistenza della vostra linea se \u00e8 alta. Una treccia a 4 fili avr\u00e0 quindi meno resistenza di un modello a 12 fili. Questo dovrebbe essere preso in considerazione a seconda del pesce che si vuole catturare.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Usare una buona linea<\/h2>\n\n\n\n<p>Affinch\u00e9 la tua <strong>treccia da pesca<\/strong> sia efficace, \u00e8 necessario utilizzare un buon pezzo di lenza. Lo scopo della lenza \u00e8 di rendere la tua lenza poco appariscente per il pesce. La punta della lenza sar\u00e0 fatta di materiali come il fluorocarbonio. Questo ha il vantaggio di essere trasparente.<\/p>\n\n\n\n<p>Il pesce non sar\u00e0 in grado di vedere che l&#8217;esca \u00e8 collegata alla vostra linea. I dettagli della linea sono il materiale di cui \u00e8 fatta, ma anche la sua forza. Con un buon diametro, ci si pu\u00f2 aspettare che catturi bene un pesce enorme. Anche la lunghezza deve essere scelta con attenzione, soprattutto nella pesca come il surfcasting.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La treccia \u00e8 uno degli elementi che vi sar\u00e0 di grande aiuto quando si tratta di pesca. Affinch\u00e9 vi serva al meglio, \u00e8 importante sceglierlo con cura. Se prendete le iniziative giuste per questo accessorio, sarete in grado di catturare grandi pesci nel migliore dei modi. La differenza tra nylon e filo intrecciato Per pescare &hellip; <a href=\"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Come pescare con la treccia?&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":136,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attrezzatura-da-pesca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come pescare con la treccia? - Fishy-Style<\/title>\n<meta name=\"description\" content=\"La treccia \u00e8 uno degli elementi che vi sar\u00e0 di grande aiuto quando si tratta di pesca. Affinch\u00e9 vi serva al meglio, \u00e8 importante sceglierlo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come pescare con la treccia? - Fishy-Style\" \/>\n<meta property=\"og:description\" content=\"La treccia \u00e8 uno degli elementi che vi sar\u00e0 di grande aiuto quando si tratta di pesca. Affinch\u00e9 vi serva al meglio, \u00e8 importante sceglierlo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fishy-Style\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-16T13:04:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-20T14:34:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.fishy-style.com\/wp-content\/uploads\/2021\/12\/empe06150m-tranche_1200x1200.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin6548\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin6548\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/2021\\\/12\\\/16\\\/come-pescare-con-la-treccia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/2021\\\/12\\\/16\\\/come-pescare-con-la-treccia\\\/\"},\"author\":{\"name\":\"admin6548\",\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/#\\\/schema\\\/person\\\/4f807833ebf28c536e4fa1a1e80fcac6\"},\"headline\":\"Come pescare con la treccia?\",\"datePublished\":\"2021-12-16T13:04:49+00:00\",\"dateModified\":\"2021-12-20T14:34:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/2021\\\/12\\\/16\\\/come-pescare-con-la-treccia\\\/\"},\"wordCount\":444,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/2021\\\/12\\\/16\\\/come-pescare-con-la-treccia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fishy-style.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/empe06150m-tranche_1200x1200.jpg\",\"articleSection\":[\"ATTREZZATURA DA PESCA\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/2021\\\/12\\\/16\\\/come-pescare-con-la-treccia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/2021\\\/12\\\/16\\\/come-pescare-con-la-treccia\\\/\",\"url\":\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/2021\\\/12\\\/16\\\/come-pescare-con-la-treccia\\\/\",\"name\":\"Come pescare con la treccia? - Fishy-Style\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/2021\\\/12\\\/16\\\/come-pescare-con-la-treccia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/2021\\\/12\\\/16\\\/come-pescare-con-la-treccia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fishy-style.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/empe06150m-tranche_1200x1200.jpg\",\"datePublished\":\"2021-12-16T13:04:49+00:00\",\"dateModified\":\"2021-12-20T14:34:49+00:00\",\"description\":\"La treccia \u00e8 uno degli elementi che vi sar\u00e0 di grande aiuto quando si tratta di pesca. Affinch\u00e9 vi serva al meglio, \u00e8 importante sceglierlo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/2021\\\/12\\\/16\\\/come-pescare-con-la-treccia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/2021\\\/12\\\/16\\\/come-pescare-con-la-treccia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/2021\\\/12\\\/16\\\/come-pescare-con-la-treccia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fishy-style.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/empe06150m-tranche_1200x1200.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fishy-style.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/empe06150m-tranche_1200x1200.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"tresse p\u00eache\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/2021\\\/12\\\/16\\\/come-pescare-con-la-treccia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.fishy-style.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come pescare con la treccia?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/#website\",\"url\":\"https:\\\/\\\/www.fishy-style.com\\\/\",\"name\":\"Fishy-Style\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fishy-style.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/#organization\",\"name\":\"Fishy-Style\",\"url\":\"https:\\\/\\\/www.fishy-style.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fishy-style.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-fishy-style.webp\",\"contentUrl\":\"https:\\\/\\\/www.fishy-style.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-fishy-style.webp\",\"width\":240,\"height\":240,\"caption\":\"Fishy-Style\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fishy-style.com\\\/#\\\/schema\\\/person\\\/4f807833ebf28c536e4fa1a1e80fcac6\",\"name\":\"admin6548\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0fbfb615b5d1b5ee2bc8c1bed1d7f792494b050a95e7848e61de9f6791cb3d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0fbfb615b5d1b5ee2bc8c1bed1d7f792494b050a95e7848e61de9f6791cb3d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0fbfb615b5d1b5ee2bc8c1bed1d7f792494b050a95e7848e61de9f6791cb3d3?s=96&d=mm&r=g\",\"caption\":\"admin6548\"},\"sameAs\":[\"http:\\\/\\\/www.fishy-style.com\"],\"url\":\"https:\\\/\\\/www.fishy-style.com\\\/it\\\/index.php\\\/author\\\/admin6548\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come pescare con la treccia? - Fishy-Style","description":"La treccia \u00e8 uno degli elementi che vi sar\u00e0 di grande aiuto quando si tratta di pesca. Affinch\u00e9 vi serva al meglio, \u00e8 importante sceglierlo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/","og_locale":"it_IT","og_type":"article","og_title":"Come pescare con la treccia? - Fishy-Style","og_description":"La treccia \u00e8 uno degli elementi che vi sar\u00e0 di grande aiuto quando si tratta di pesca. Affinch\u00e9 vi serva al meglio, \u00e8 importante sceglierlo","og_url":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/","og_site_name":"Fishy-Style","article_published_time":"2021-12-16T13:04:49+00:00","article_modified_time":"2021-12-20T14:34:49+00:00","og_image":[{"width":1200,"height":1200,"url":"http:\/\/www.fishy-style.com\/wp-content\/uploads\/2021\/12\/empe06150m-tranche_1200x1200.jpg","type":"image\/jpeg"}],"author":"admin6548","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin6548","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/#article","isPartOf":{"@id":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/"},"author":{"name":"admin6548","@id":"https:\/\/www.fishy-style.com\/#\/schema\/person\/4f807833ebf28c536e4fa1a1e80fcac6"},"headline":"Come pescare con la treccia?","datePublished":"2021-12-16T13:04:49+00:00","dateModified":"2021-12-20T14:34:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/"},"wordCount":444,"commentCount":0,"publisher":{"@id":"https:\/\/www.fishy-style.com\/#organization"},"image":{"@id":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fishy-style.com\/wp-content\/uploads\/2021\/12\/empe06150m-tranche_1200x1200.jpg","articleSection":["ATTREZZATURA DA PESCA"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/","url":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/","name":"Come pescare con la treccia? - Fishy-Style","isPartOf":{"@id":"https:\/\/www.fishy-style.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/#primaryimage"},"image":{"@id":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fishy-style.com\/wp-content\/uploads\/2021\/12\/empe06150m-tranche_1200x1200.jpg","datePublished":"2021-12-16T13:04:49+00:00","dateModified":"2021-12-20T14:34:49+00:00","description":"La treccia \u00e8 uno degli elementi che vi sar\u00e0 di grande aiuto quando si tratta di pesca. Affinch\u00e9 vi serva al meglio, \u00e8 importante sceglierlo","breadcrumb":{"@id":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/#primaryimage","url":"https:\/\/www.fishy-style.com\/wp-content\/uploads\/2021\/12\/empe06150m-tranche_1200x1200.jpg","contentUrl":"https:\/\/www.fishy-style.com\/wp-content\/uploads\/2021\/12\/empe06150m-tranche_1200x1200.jpg","width":1200,"height":1200,"caption":"tresse p\u00eache"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fishy-style.com\/it\/index.php\/2021\/12\/16\/come-pescare-con-la-treccia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.fishy-style.com\/"},{"@type":"ListItem","position":2,"name":"Come pescare con la treccia?"}]},{"@type":"WebSite","@id":"https:\/\/www.fishy-style.com\/#website","url":"https:\/\/www.fishy-style.com\/","name":"Fishy-Style","description":"","publisher":{"@id":"https:\/\/www.fishy-style.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fishy-style.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fishy-style.com\/#organization","name":"Fishy-Style","url":"https:\/\/www.fishy-style.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fishy-style.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.fishy-style.com\/wp-content\/uploads\/2022\/02\/cropped-fishy-style.webp","contentUrl":"https:\/\/www.fishy-style.com\/wp-content\/uploads\/2022\/02\/cropped-fishy-style.webp","width":240,"height":240,"caption":"Fishy-Style"},"image":{"@id":"https:\/\/www.fishy-style.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.fishy-style.com\/#\/schema\/person\/4f807833ebf28c536e4fa1a1e80fcac6","name":"admin6548","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e0fbfb615b5d1b5ee2bc8c1bed1d7f792494b050a95e7848e61de9f6791cb3d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0fbfb615b5d1b5ee2bc8c1bed1d7f792494b050a95e7848e61de9f6791cb3d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0fbfb615b5d1b5ee2bc8c1bed1d7f792494b050a95e7848e61de9f6791cb3d3?s=96&d=mm&r=g","caption":"admin6548"},"sameAs":["http:\/\/www.fishy-style.com"],"url":"https:\/\/www.fishy-style.com\/it\/index.php\/author\/admin6548\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fishy-style.com\/it\/index.php\/wp-json\/wp\/v2\/posts\/229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fishy-style.com\/it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fishy-style.com\/it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fishy-style.com\/it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fishy-style.com\/it\/index.php\/wp-json\/wp\/v2\/comments?post=229"}],"version-history":[{"count":2,"href":"https:\/\/www.fishy-style.com\/it\/index.php\/wp-json\/wp\/v2\/posts\/229\/revisions"}],"predecessor-version":[{"id":231,"href":"https:\/\/www.fishy-style.com\/it\/index.php\/wp-json\/wp\/v2\/posts\/229\/revisions\/231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fishy-style.com\/it\/index.php\/wp-json\/wp\/v2\/media\/136"}],"wp:attachment":[{"href":"https:\/\/www.fishy-style.com\/it\/index.php\/wp-json\/wp\/v2\/media?parent=229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fishy-style.com\/it\/index.php\/wp-json\/wp\/v2\/categories?post=229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fishy-style.com\/it\/index.php\/wp-json\/wp\/v2\/tags?post=229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}